{"id":10648,"date":"2024-01-18T16:01:55","date_gmt":"2024-01-18T21:01:55","guid":{"rendered":"https:\/\/www.ericadventures.com\/cusco\/rafting\/rafting-rainbow-mountain-2days-copy\/"},"modified":"2025-11-03T18:00:32","modified_gmt":"2025-11-03T23:00:32","slug":"rafting-en-el-rio-urubamba-2-dias","status":"publish","type":"page","link":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/","title":{"rendered":"2D Rafting en el r\u00edo Urubamba"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"310\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795-400x310-5.jpg\" alt=\"\" class=\"wp-image-30425\" style=\"aspect-ratio:1.7777777777777777;object-fit:cover;width:416px;height:auto\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795-400x310-5.jpg 400w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795-400x310-5-300x233.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">RAFTING EN AGUAS BLANCAS &#8211; CUSCO PERU<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El r\u00edo Urubamba corre desde las altas cordilleras andinas hasta el Valle Sagrado de los Incas, pasando por Machu Picchu y adentr\u00e1ndose en la selva. Tiene aguas bravas emocionantes seg\u00fan la secci\u00f3n del r\u00edo que se recorra y la \u00e9poca del a\u00f1o. Una de nuestras secciones de rafting m\u00e1s populares durante la temporada es la secci\u00f3n \u201cChuqui\u201d del r\u00edo en el Alto Urubamba. Hay buenos r\u00e1pidos de clase IIl y el agua no est\u00e1 contaminada, como desafortunadamente lo est\u00e1n las secciones del r\u00edo Huambutio y Ollantaytambo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ITINERARIO<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">DIA 1<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lo recogeremos en su hotel con nuestro transporte privado, luego de una hora y media de viaje llegaremos al punto de partida en las orillas de Cusipata River Lodge; nuestro campamento privado. Nuestros gu\u00edas profesionales de Rafting le dar\u00e1n una charla de seguridad y le proporcionar\u00e1n todo el equipo adecuado para realizar Rafting.<br>Estar\u00e1s flotando por aproximadamente dos horas, corriendo r\u00e1pidos de clase II, tipo introductorio. Como juguetes adicionales para jugar en esta secci\u00f3n del r\u00edo tendr\u00e1s Hydrospeeds y kayaks inflables. Luego, llegaremos al punto de partida y nos dirigiremos a nuestro albergue para almorzar. Luego, como opci\u00f3n, puedes hacer tirolesa a trav\u00e9s del r\u00edo. Pasar\u00e1s la noche en el \u201cLODGE\u201d, donde tenemos c\u00f3modas habitaciones dobles con ba\u00f1o privado, te quedar\u00e1s dormido bajo el susurro del r\u00edo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">DIA 2<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Rafting Down the Urubamba\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/O7Ic7rMmR6M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">INCLUIDO<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Transporte desde Cusco hasta el embarcadero del r\u00edo<\/li>\n\n\n\n<li>Todo el equipo de rafting, como casco, chaleco salvavidas, remo, balsa autovaciante.<\/li>\n\n\n\n<li>Chaqueta antisalpicaduras, traje de neopreno<\/li>\n\n\n\n<li>Gu\u00eda de rafting profesional de habla inglesa<\/li>\n\n\n\n<li>Almuerzo tipo picnic<\/li>\n\n\n\n<li>Transporte de regreso desde el r\u00edo<\/li>\n\n\n\n<li>Habitaci\u00f3n doble o individual con ba\u00f1o privado.<\/li>\n\n\n\n<li>01 desayuno, 02 almuerzos, 01 cena<\/li>\n\n\n\n<li>Duchas de agua caliente, ba\u00f1os, chimenea.<\/li>\n\n\n\n<li>Contamos con un lindo bar y \u00e1rea de socializaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Recomendamos traer<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un conjunto completo de ropa seca.<\/li>\n\n\n\n<li>Un par de sandalias o tenis para el r\u00edo.<\/li>\n\n\n\n<li>Sombrero, bloqueador solar<\/li>\n\n\n\n<li>Una toalla peque\u00f1a<\/li>\n\n\n\n<li>Un traje de ba\u00f1o para usar debajo del traje de neopreno.<\/li>\n\n\n\n<li>Botella de agua personal y snacks.<\/li>\n\n\n\n<li>Ropa de abrigo para la noche (polar, pantalones largos)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Otros que debes conocer:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La hora de recogida por la ma\u00f1ana con nuestro autob\u00fas es una hora aproximada (seg\u00fan el tr\u00e1fico y el tama\u00f1o del grupo)<\/li>\n\n\n\n<li>Obligatorio para poder Nadar<\/li>\n\n\n\n<li>El nivel del r\u00edo puede cambiar seg\u00fan la temporada.<\/li>\n\n\n\n<li>Nos reservamos el derecho de cambiar el itinerario seg\u00fan la seguridad de nuestros clientes.<\/li>\n\n\n\n<li>El servicio de Video y Fotograf\u00edas es un servicio opcional que a veces brinda un fot\u00f3grafo kayakista de nuestra tripulaci\u00f3n, normalmente despu\u00e9s de tu recorrido, podr\u00e1s comprarlo (el CD), solo p\u00e1galo una vez que tengas este producto contigo, despu\u00e9s de cada viaje borramos fotos y videos, por lo tanto, no podemos garantizar la existencia de videos e im\u00e1genes por un largo per\u00edodo de tiempo.<\/li>\n\n\n\n<li>Los ni\u00f1os deben venir con sus padres, tambi\u00e9n tenemos equipamiento para ni\u00f1os.<\/li>\n\n\n\n<li>Si tiene necesidades especiales, inf\u00f3rmenos con antelaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">NOTAS:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En nuestros servicios compartidos, recogeremos a nuestros clientes en su hotel siempre que \u00e9ste est\u00e9 situado en el centro de la ciudad.<\/li>\n\n\n\n<li>En nuestros servicios compartidos, al finalizar el tour, dejamos a nuestros clientes en un lugar cercano a la Plaza de Armas, ya que es m\u00e1s f\u00e1cil ir caminando que en auto por el tr\u00e1fico. Si su hotel est\u00e1 lejos del centro, lleve algo de efectivo para tomar un taxi.<\/li>\n\n\n\n<li>Los horarios de recogida y devoluci\u00f3n son referenciales, esto depender\u00e1 del tr\u00e1fico que se pueda encontrar en las calles o retraso de los dem\u00e1s clientes, nuestro asistente llegar\u00e1 a tiempo pero en ocasiones el transporte podr\u00eda retrasarse algunos minutos.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">PRECIO<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Precios en D\u00f3lares Americanos por persona<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MAPA<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafing-2-days-7-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"30431\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafing-2-days-7-150x150.jpg\" alt=\"\" class=\"wp-image-30431\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>GALER\u00cdA DE FOTOS<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-7 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours8-2-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"359\" data-id=\"30436\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours8-2-6.jpg\" alt=\"\" class=\"wp-image-30436\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours8-2-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours8-2-6-300x224.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-2-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"359\" data-id=\"30440\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-2-6.jpg\" alt=\"\" class=\"wp-image-30440\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-2-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-2-6-300x224.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-apurimac-river-rafting-adventure-tour5-2-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"359\" data-id=\"30451\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-apurimac-river-rafting-adventure-tour5-2-6.jpg\" alt=\"\" class=\"wp-image-30451\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-apurimac-river-rafting-adventure-tour5-2-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-apurimac-river-rafting-adventure-tour5-2-6-300x224.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting-rainbow-mountain-07-1-11.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" data-id=\"30456\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting-rainbow-mountain-07-1-11.jpg\" alt=\"\" class=\"wp-image-30456\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting-rainbow-mountain-07-1-11.jpg 600w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting-rainbow-mountain-07-1-11-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-1-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"359\" data-id=\"30446\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-1-6.jpg\" alt=\"\" class=\"wp-image-30446\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-1-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-apurimac-river-rafting-tours3-1-6-300x224.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamaba-river-rafting-tours1-1-7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30461\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamaba-river-rafting-tours1-1-7.jpg\" alt=\"\" class=\"wp-image-30461\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamaba-river-rafting-tours1-1-7.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamaba-river-rafting-tours1-1-7-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamba-river-rafting-tours6-1-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30466\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamba-river-rafting-tours6-1-6.jpg\" alt=\"\" class=\"wp-image-30466\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamba-river-rafting-tours6-1-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/peru-cusco-urubamba-river-rafting-tours6-1-6-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FORMULARIO DE CONTACTO<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6169-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"6169\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/10648#wpcf7-f6169-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6169\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6169-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpcf7-turnstile cf-turnstile\" data-sitekey=\"0x4AAAAAACZ2CLxkDaDac8NW\" data-response-field-name=\"_wpcf7_turnstile_response\"><\/div>\n\n<div class=\"formt\">\n    <span class=\"textform\"> Para reservas o m\u00e1s informaci\u00f3n por favor complete el siguiente formulario de cliente\/hu\u00e9sped: <\/span>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/10648\" type=\"hidden\" name=\"Url_Tour\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"es\" type=\"hidden\" name=\"Idioma\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"01\/09\/2026 23:36:42\" type=\"hidden\" name=\"Fecha_Hora\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"216.73.216.62\" type=\"hidden\" name=\"Ip\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"2D Rafting en el r\u00edo Urubamba\" type=\"hidden\" name=\"Nombre_Tour\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"1\" type=\"hidden\" name=\"enviar_excel\" \/>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Nombre: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Nombre\" \/><\/span>\n        <\/div>\n        <div>\n            <label>Email: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Emails\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"Emails\" \/><\/span>\n        <\/div>\n    <\/div>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Pa\u00eds: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Pais\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Pais\" \/><\/span>\n        <\/div>\n        <div>\n            <label>Tel\u00e9fono - Whatsapp: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Whatsapp\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-phonetext wpcf7-text wpcf7-validates-as-phonetext\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Whatsapp\" \/><input type=\"hidden\" name=\"Whatsapp-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span>\n        <\/div>\n    <\/div>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Cantidad de Personas Adultas: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Adultos\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Adultos\"><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><option value=\"6\">6<\/option><option value=\"7\">7<\/option><option value=\"8\">8<\/option><option value=\"9\">9<\/option><option value=\"10\">10<\/option><option value=\"11\">11<\/option><option value=\"12 a m\u00e1s\">12 a m\u00e1s<\/option><\/select><\/span>\n        <\/div>\n        <div>\n            <label>Cantidad de Ni\u00f1os: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Ninos\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Ninos\"><option value=\"0\">0<\/option><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><option value=\"6\">6<\/option><option value=\"7\">7<\/option><option value=\"8\">8<\/option><option value=\"9\">9<\/option><option value=\"10\">10<\/option><option value=\"11\">11<\/option><option value=\"12 a m\u00e1s\">12 a m\u00e1s<\/option><\/select><\/span>\n        <\/div>\n    <\/div>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Fecha de Inicio del Tour: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Inicio\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" id=\"inicio\" min=\"2026-09-01\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"Inicio\" \/><\/span>\n        <\/div>\n        <div>\n            <label>Fecha de Finalizaci\u00f3n del Tour: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Final\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" id=\"final\" min=\"2026-09-01\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"Final\" \/><\/span>\n        <\/div>\n    <\/div>\n    \n    <div>\n        <label>Comentarios o preguntas: <\/label>\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"Mensaje\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Por favor especifica el tipo de SERVICIO\/TOUR que deseas realizar\" name=\"Mensaje\"><\/textarea><\/span>\n    <\/div>\n    \n    <input class=\"wpcf7-form-control wpcf7-submit has-spinner btnsend\" type=\"submit\" value=\"ENVIAR MENSAJE\" \/>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>RAFTING EN AGUAS BLANCAS &#8211; CUSCO PERU El r\u00edo Urubamba corre desde las altas cordilleras andinas hasta el Valle Sagrado [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21403,"parent":3504,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-tour.php","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-10648","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>2D Rafting en el r\u00edo Urubamba<\/title>\n<meta name=\"description\" content=\"Rafting on the Urubamba River in Cusco Peru, enjoy this exciting trip near the Sacred Valley, where we will run different rapids.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2D Rafting en el r\u00edo Urubamba\" \/>\n<meta property=\"og:description\" content=\"Rafting on the Urubamba River in Cusco Peru, enjoy this exciting trip near the Sacred Valley, where we will run different rapids.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Eric Adventures\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T23:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/\",\"url\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/\",\"name\":\"2D Rafting en el r\u00edo Urubamba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ericadventures.com\\\/wp-content\\\/uploads\\\/Optimized-B27I5795.jpg\",\"datePublished\":\"2024-01-18T21:01:55+00:00\",\"dateModified\":\"2025-11-03T23:00:32+00:00\",\"description\":\"Rafting on the Urubamba River in Cusco Peru, enjoy this exciting trip near the Sacred Valley, where we will run different rapids.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ericadventures.com\\\/wp-content\\\/uploads\\\/Optimized-B27I5795.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ericadventures.com\\\/wp-content\\\/uploads\\\/Optimized-B27I5795.jpg\",\"width\":1200,\"height\":799,\"caption\":\"Rafting en el r\u00edo Urubamba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/rafting-en-el-rio-urubamba-2-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tours en Cusco\",\"item\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rafting\",\"item\":\"https:\\\/\\\/www.ericadventures.com\\\/es\\\/cusco\\\/rafting\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"2D Rafting en el r\u00edo Urubamba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/\",\"name\":\"Eric Adventures\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/#organization\"},\"alternateName\":\"Eric Adventures\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/#organization\",\"name\":\"Eric Adventures\",\"url\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ericadventures.com\\\/wp-content\\\/uploads\\\/logo-ericadventures.png\",\"contentUrl\":\"https:\\\/\\\/www.ericadventures.com\\\/wp-content\\\/uploads\\\/logo-ericadventures.png\",\"width\":500,\"height\":106,\"caption\":\"Eric Adventures\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ericadventures.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2D Rafting en el r\u00edo Urubamba","description":"Rafting on the Urubamba River in Cusco Peru, enjoy this exciting trip near the Sacred Valley, where we will run different rapids.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/","og_locale":"es_ES","og_type":"article","og_title":"2D Rafting en el r\u00edo Urubamba","og_description":"Rafting on the Urubamba River in Cusco Peru, enjoy this exciting trip near the Sacred Valley, where we will run different rapids.","og_url":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/","og_site_name":"Eric Adventures","article_modified_time":"2025-11-03T23:00:32+00:00","og_image":[{"width":1200,"height":799,"url":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/","url":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/","name":"2D Rafting en el r\u00edo Urubamba","isPartOf":{"@id":"https:\/\/www.ericadventures.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/#primaryimage"},"image":{"@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795.jpg","datePublished":"2024-01-18T21:01:55+00:00","dateModified":"2025-11-03T23:00:32+00:00","description":"Rafting on the Urubamba River in Cusco Peru, enjoy this exciting trip near the Sacred Valley, where we will run different rapids.","breadcrumb":{"@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/#primaryimage","url":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795.jpg","contentUrl":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795.jpg","width":1200,"height":799,"caption":"Rafting en el r\u00edo Urubamba"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rafting-en-el-rio-urubamba-2-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ericadventures.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tours en Cusco","item":"https:\/\/www.ericadventures.com\/es\/cusco\/"},{"@type":"ListItem","position":3,"name":"Rafting","item":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/"},{"@type":"ListItem","position":4,"name":"2D Rafting en el r\u00edo Urubamba"}]},{"@type":"WebSite","@id":"https:\/\/www.ericadventures.com\/en\/#website","url":"https:\/\/www.ericadventures.com\/en\/","name":"Eric Adventures","description":"","publisher":{"@id":"https:\/\/www.ericadventures.com\/en\/#organization"},"alternateName":"Eric Adventures","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ericadventures.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ericadventures.com\/en\/#organization","name":"Eric Adventures","url":"https:\/\/www.ericadventures.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ericadventures.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/logo-ericadventures.png","contentUrl":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/logo-ericadventures.png","width":500,"height":106,"caption":"Eric Adventures"},"image":{"@id":"https:\/\/www.ericadventures.com\/en\/#\/schema\/logo\/image\/"}}]}},"coauthors":[],"author_meta":{"author_link":"https:\/\/www.ericadventures.com\/es\/author\/marilyn\/","display_name":"Marilyn Ayma Gomez"},"relative_dates":{"created":"Publicado 3 a\u00f1os hace","modified":"Actualizado 10 meses hace"},"absolute_dates":{"created":"Publicado el enero 18, 2024","modified":"Actualizado el noviembre 3, 2025"},"absolute_dates_time":{"created":"Publicado el enero 18, 2024 4:01 pm","modified":"Actualizado el noviembre 3, 2025 6:00 pm"},"featured_img_caption":"","featured_img":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/Optimized-B27I5795.jpg","series_order":"","_links":{"self":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/10648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/comments?post=10648"}],"version-history":[{"count":5,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/10648\/revisions"}],"predecessor-version":[{"id":42887,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/10648\/revisions\/42887"}],"up":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/3504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/media\/21403"}],"wp:attachment":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/media?parent=10648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}