{"id":12715,"date":"2024-02-23T10:29:44","date_gmt":"2024-02-23T15:29:44","guid":{"rendered":"https:\/\/www.ericadventures.com\/cusco\/rafting\/cotahuasi-river-deepest-canyon-world\/"},"modified":"2025-11-05T11:32:23","modified_gmt":"2025-11-05T16:32:23","slug":"rio-cotahuasi-canon-profundo-mundo","status":"publish","type":"page","link":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/","title":{"rendered":"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting009-5.jpg\" alt=\"\" class=\"wp-image-30589\" style=\"aspect-ratio:1.7777777777777777;object-fit:cover;width:416px;height:auto\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting009-5.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting009-5-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Nivel<\/strong>: challenge. Clase: r\u00e1pidos 4 y 5. No es necesaria experiencia previa, pero una buena condici\u00f3n f\u00edsica es esencial. A petici\u00f3n, excursiones a pie o a caballo (2 d\u00edas).<br><strong>Descripci\u00f3n<\/strong>: salvaje y desafiante. Hermoso ca\u00f1\u00f3n con sitios arqueol\u00f3gicos. R\u00e1pidas duras e intensas.<br><strong>Punto de encuentro<\/strong>:&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/machupicchu\/cusco-peru-canotaje\/canotaje-selva-tambopata-9-dias.html\" target=\"_blank\" rel=\"noreferrer noopener\">Arequipa<\/a>&nbsp;(sur del&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/informacion-util-peru.html\" target=\"_blank\" rel=\"noreferrer noopener\">Per\u00fa<\/a>).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-itinerario\">ITINERARIO <\/h2>\n\n\n\n<p><strong>D\u00eda 1:&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/machupicchu\/cusco-peru-canotaje\/canotaje-selva-tambopata-9-dias.html\" target=\"_blank\" rel=\"noreferrer noopener\">Arequipa<\/a>, la ciudad blanca. Sur del&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/informacion-util-peru.html\" target=\"_blank\" rel=\"noreferrer noopener\">Per\u00fa<\/a>.<\/strong><\/p>\n\n\n\n<p>Nuestro viaje comienza en la ciudad de&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/machupicchu\/cusco-peru-canotaje\/canotaje-selva-tambopata-9-dias.html\" target=\"_blank\" rel=\"noreferrer noopener\">Arequipa<\/a>, la segunda ciudad m\u00e1s grande en el&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/informacion-util-peru.html\" target=\"_blank\" rel=\"noreferrer noopener\">Per\u00fa<\/a>&nbsp;y principal centro urbano en la regi\u00f3n suroeste del pa\u00eds, ubicada a unos 750 kil\u00f3metros (500 millas aproximadamente) en l\u00ednea recta &#8211; una hora de avi\u00f3n &#8211; de&nbsp;<strong>Lima<\/strong>. Por la tarde haremos un recorrido por la ciudad de cerca de 500 a\u00f1os de antig\u00fcedad, recientemente proclamada Patrimonio de la Humanidad por la&nbsp;<strong>U.N.E.S.C.O<\/strong>.. Entre los principales atractivos hay el famoso Convento de<strong>Santa Catalina<\/strong>, as\u00ed como el Museo, donde se puede ver el cad\u00e1ver momificado de la joven inca (conocido en los tiempos actuales como \u00abJuanita\u00bb), que se encontr\u00f3 hace algunos a\u00f1os en la parte superior del pico nevado Ampato, cerca del&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/machupicchu\/cusco-peru-canotaje\/canotaje-selva-tambopata-9-dias.html\" target=\"_blank\" rel=\"noreferrer noopener\">Ca\u00f1on del Colca<\/a>.<\/p>\n\n\n\n<p><strong>D\u00eda 2:&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/machupicchu\/cusco-peru-canotaje\/canotaje-selva-tambopata-9-dias.html\" target=\"_blank\" rel=\"noreferrer noopener\">Arequipa<\/a>. Viaje terrestre a Cotahuasi<\/strong><\/p>\n\n\n\n<p>Hoy salimos de la ciudad de&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/machupicchu\/cusco-peru-canotaje\/canotaje-selva-tambopata-9-dias.html\" target=\"_blank\" rel=\"noreferrer noopener\">Arequipa<\/a>, hacia la ciudad de&nbsp;<strong>Cotahuasi<\/strong>. Es un largo viaje en veh\u00edculo 4&#215;4 a trav\u00e9s de los Andes. En el camino pasaremos por un paso de monta\u00f1a a una altitud de 4.000 metros (unos 13.400 pies) sobre el nivel del mar, llegar a las inmediaciones del imponente nevado Coropuna (la segunda monta\u00f1a m\u00e1s alta en el&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/informacion-util-peru.html\" target=\"_blank\" rel=\"noreferrer noopener\">Per\u00fa<\/a>&nbsp;y entre las diez m\u00e1s altas en el hemisferio occidental) y pasaremos por varias, antiguas ciudades y pueblos donde el tiempo parece haberse detenido hace siglos. Despu\u00e9s de diez horas de conducci\u00f3n llegamos a&nbsp;<strong>Cotahuasi<\/strong>, donde pasaremos la noche en un albergue local. (Desayuno y almuerzo).<\/p>\n\n\n\n<p><strong>D\u00eda 3: la ciudad de Cotahuasi y los Ba\u00f1os de Luicho<\/strong><\/p>\n\n\n\n<p>Durante la ma\u00f1ana hacemos una excursi\u00f3n al&nbsp;<strong>Ca\u00f1\u00f3n Amana<\/strong>, cruzando el antiguo puente de&nbsp;<strong>Chuquito<\/strong>, que remonta a la \u00e9poca pre-inca. Por la tarde, visitaremos el pueblo de Cotahuasi. Este tambi\u00e9n es un sito urbano secular. La zona que lo rodea es un refugio ideal y h\u00e1bitat para las especies en peligro de extinci\u00f3n y protegidas de la fauna de los Andes, como vicu\u00f1as y c\u00f3ndores: gracias a sus caracter\u00edsticas culturales y arqueol\u00f3gicas, ha sido proclamada Reserva nacional de Turismo (Zona Reserva nacional tur\u00edstica) en 1988. (Pensi\u00f3n completa).<\/p>\n\n\n\n<p><strong>D\u00eda 4: caminata de acercamiento al r\u00edo, llegando al punto de entrada Velinga<\/strong><\/p>\n\n\n\n<p>Nos dirigimos en coche hasta el final del camino (y as\u00ed nos ahorramos dos horas de caminata). Despu\u00e9s de llegar al puente de Sipia, nos encontramos con los \u00ab<strong>burros<\/strong>\u00ab, los burros de carga y sus arrieros, que en adelante cargar\u00e1n y se llevar\u00e1n nuestro equipo y el bote hasta la entrada del r\u00edo. Despu\u00e9s de siete horas de caminata, durante la cual cruzamos la<strong>catarata de Sipia<\/strong>, una cascada con una ca\u00edda vertical de 150 metros (unos 495 pies), y un bosque de cacti gigantes, al final llegamos a la aldea de Velinga y al nuestro primero acampar a lo largo del r\u00edo. (Pensi\u00f3n completa)<\/p>\n\n\n\n<p><strong>D\u00eda 5: R\u00edo 1. Entrada y rafting Cotahuasi<\/strong><\/p>\n\n\n\n<p>Llegada la ma\u00f1ana, preparamos todos nuestros equipos y las otras infraestructuras log\u00edsticas, inflamos los botes, gustamos nuestra comida y nos ponemos en el r\u00edo. Durante las dos horas siguientes remaremos a lo largo del r\u00edo durante 4 kil\u00f3metros (cerca de 2,7 millas) con r\u00e1pidos de clase III y IV, y as\u00ed llegaremos a nuestro segundo campamento. (Pensi\u00f3n completa)<\/p>\n\n\n\n<p><strong>D\u00edas 6-9: R\u00edo 2. Rafting en el r\u00edo.<\/strong><\/p>\n\n\n\n<p>Despu\u00e9s de un rico y saludable desayuno comenzamos nuestro rafting. Vamos a superar muchos r\u00e1pidos de clase IV y algunos de clase V en los pr\u00f3ximos cuatro d\u00edas. Entre un r\u00e1pido y el otro vamos a tener muchas oportunidades para caminar y explorar las muchas sorprendentes ruinas pre-incas e incas que encontraremos durante nuestro descenso hacia el&nbsp;<strong>Oc\u00e9ano Pac\u00edfico<\/strong>. El ca\u00f1\u00f3n es tambi\u00e9n el hogar de una abundante poblaci\u00f3n de aves, \u00e1guilas y muchos c\u00f3ndores. Cada noche los gu\u00edas preparar\u00e1n una comida saludable y&nbsp; camparemos bajo el cielo estrellado del sur.<\/p>\n\n\n\n<p>Durante los pr\u00f3ximos cuatro d\u00edas vamos a navegar hacia abajo por 65 kil\u00f3metros (unas 44 millas) de emocionantes y divertidos r\u00e1pidos de clase III, IV y V. (Pensi\u00f3n completa).<\/p>\n\n\n\n<p><strong>D\u00eda 10: tramo final de la navegaci\u00f3n, y salida del r\u00edo<\/strong><\/p>\n\n\n\n<p>En este d\u00eda cubrimos los \u00faltimos 20 km. (cerca de 13 millas) de nuestra expedici\u00f3n por el r\u00edo.<\/p>\n\n\n\n<p>Este \u00faltimo d\u00eda en nuestros botes lo pasaremos en el&nbsp;<strong>R\u00edo Oco\u00f1a<\/strong>, con algunos r\u00e1pidos de clase III y IV. El r\u00edo cambia su nombre a la confluencia con el&nbsp;<strong>R\u00edo Maran<\/strong>. Aqu\u00ed, la naturaleza del r\u00edo cambia a medida que descendemos hacia Iquip\u00ed (cerca del&nbsp;<strong>Oc\u00e9ano Pac\u00edfico<\/strong>), donde nuestro transporte nos estar\u00e1 esperando para llevarnos en&nbsp;<a href=\"https:\/\/www.ericadventures.com\/peru\/machupicchu\/cusco-peru-canotaje\/canotaje-selva-tambopata-9-dias.html\" target=\"_blank\" rel=\"noreferrer noopener\">Arequipa<\/a>&nbsp;y a nuestro hotel en la ciudad. 4-5 horas de viaje de vuelta. (Desayuno y almuerzo).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-incluye\">INCLUYE<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>informaciones preliminares, incluyendo lo que se debe llevar, etc.<\/li>\n\n\n\n<li>contacto y coordinaci\u00f3n constantes desde el momento de efectuar la reserva, y mientras que est\u00e1n en el&nbsp;<strong>Per\u00fa<\/strong><\/li>\n\n\n\n<li>traslado en bus privado hacia&nbsp;<strong>Arequipa<\/strong>&nbsp;\/ Cotahuasi y Iquipi \/&nbsp;<strong>Arequipa<\/strong><\/li>\n\n\n\n<li>todas las comidas y los snacks durante la expedici\u00f3n, como se indica en el programa<\/li>\n\n\n\n<li>equipo completo profesional de rafting (bolsas impermeables, trajes de neopreno, chalecos salvavidas, cascos, anorak, remos)<\/li>\n\n\n\n<li>botes inflables profesionales por rafting<\/li>\n\n\n\n<li>uno o dos kayak de seguridad con sus conductores (dependiendo del tama\u00f1o del grupo)<\/li>\n\n\n\n<li>equipo de camping e infraestructura log\u00edstica (tiendas de campa\u00f1a para dos personas)<\/li>\n\n\n\n<li>gu\u00edas de r\u00edo profesionalmente preparados y expertos (entrenados y certificados en Cursos de Liderazgo en Aire libre, Guiado en Ambiente salvaje y R\u00edos r\u00e1pidos)<\/li>\n\n\n\n<li>jinete local y mulas para llevar el equipo de Huambo a Canco<\/li>\n\n\n\n<li>respeto por el medio ambiente<\/li>\n\n\n\n<li>equipo de primeros auxilios y cuidado por los asuntos de seguridad y sus procedimientos relacionados.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-n-o-incluye\"><strong>N<\/strong>o Incluye<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>gastos no especificados y servicios imprevistos<\/li>\n\n\n\n<li>tarifas a\u00e9reas<\/li>\n\n\n\n<li>sacos de dormir y colchonetas<\/li>\n\n\n\n<li>las comidas en la ciudad de Arequipa.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-equipo-personal-esencial-que-se-recomienda-llevar-consigo\">Equipo personal esencial que se recomienda llevar consigo<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>gafas de sol<\/li>\n\n\n\n<li>protecci\u00f3n contra el sol<\/li>\n\n\n\n<li>repelente de insectos<\/li>\n\n\n\n<li>zapatos de tenis y\/o sandalias por bote con correas (Tevas o similares)<\/li>\n\n\n\n<li>traje de ba\u00f1o<\/li>\n\n\n\n<li>dos cambios de ropa<\/li>\n\n\n\n<li>ropa t\u00e9rmica<\/li>\n\n\n\n<li>toalla<\/li>\n\n\n\n<li>faro o pila m\u00e1s m\u00faltiples bater\u00edas de repuesto<\/li>\n\n\n\n<li>sombrero, gorra o tocado adecuado<\/li>\n\n\n\n<li>los medicamentos personales.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-notas\">NOTAS:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En nuestros servicios compartidos, recogeremos a nuestros clientes desde su hotel siempre y cuanto se encuentre en el centro de la ciudad.<\/li>\n\n\n\n<li>En nuestros servicios compartidos, al finalizar el tour, dejamos a nuestros clientes en un lugar cercano a la Plaza Principal, es m\u00e1s facil retornar a su hotel caminando que ir en el bus, ya que el tr\u00e1fico es terrible. Si su hotel est\u00e1 lejos del centro de la ciudad, lleve dinero extra en efectivo para tomar un taxi.<\/li>\n\n\n\n<li>Los horarios de recojo y arribo son referenciales, esto depender\u00e1 del tr\u00e1fico que se pueda encontrar en las calles o del retraso de los otros clientes, nuestro asistente llegar\u00e1 a tiempo a su hotel, pero a veces el transporte podr\u00eda retrasarse unos minutos.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-precios-por-persona-en-dolares-americanos\">PRECIOS(POR PERSONA EN D\u00d3LARES AMERICANOS)<\/h2>\n\n\n\n<p><strong>SERVICIO PRIVADO<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Precio por persona, habitaci\u00f3n doble : US$ 5485(m\u00ednimo 4 personas)<\/li>\n<\/ul>\n\n\n\n<p>*Precios referenciales sujetos a disponibilidad y temporada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mapa\">MAPA<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-thumbnail\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/cotahuasi_river_deepest_canyon_world_arequipa_peru_en-1024x496-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-id=\"30624\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/cotahuasi_river_deepest_canyon_world_arequipa_peru_en-1024x496-6-150x150.jpg\" alt=\"\" class=\"wp-image-30624\"\/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-galeria-de-fotos\"><strong>GALERIA DE FOTOS<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-6 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting008-2-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30634\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting008-2-6.jpg\" alt=\"\" class=\"wp-image-30634\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting008-2-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting008-2-6-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting005-1-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30629\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting005-1-6.jpg\" alt=\"\" class=\"wp-image-30629\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting005-1-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting005-1-6-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/image-5.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30639\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/image-5.jpeg\" alt=\"\" class=\"wp-image-30639\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/image-5.jpeg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/image-5-300x225.jpeg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting002-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30648\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting002-6.jpg\" alt=\"\" class=\"wp-image-30648\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting002-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting002-6-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting001-3-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30644\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting001-3-6.jpg\" alt=\"\" class=\"wp-image-30644\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting001-3-6.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting001-3-6-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting009-7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" data-id=\"30654\" src=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting009-7.jpg\" alt=\"\" class=\"wp-image-30654\" srcset=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting009-7.jpg 480w, https:\/\/www.ericadventures.com\/wp-content\/uploads\/rafting009-7-300x225.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-formulario-de-contacto\"><strong><strong>FORMULARIO DE CONTACTO<\/strong><\/strong><\/h2>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6169-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"6169\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/12715#wpcf7-f6169-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6169\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6169-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpcf7-turnstile cf-turnstile\" data-sitekey=\"0x4AAAAAACZ2CLxkDaDac8NW\" data-response-field-name=\"_wpcf7_turnstile_response\"><\/div>\n\n<div class=\"formt\">\n    <span class=\"textform\"> Para reservas o m\u00e1s informaci\u00f3n por favor complete el siguiente formulario de cliente\/hu\u00e9sped: <\/span>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/12715\" type=\"hidden\" name=\"Url_Tour\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"es\" type=\"hidden\" name=\"Idioma\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"13\/05\/2026 17:16:25\" type=\"hidden\" name=\"Fecha_Hora\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"216.73.217.22\" type=\"hidden\" name=\"Ip\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo\" type=\"hidden\" name=\"Nombre_Tour\" \/>\n    <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"1\" type=\"hidden\" name=\"enviar_excel\" \/>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Nombre: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Nombre\" \/><\/span>\n        <\/div>\n        <div>\n            <label>Email: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Emails\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"Emails\" \/><\/span>\n        <\/div>\n    <\/div>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Pa\u00eds: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Pais\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Pais\" \/><\/span>\n        <\/div>\n        <div>\n            <label>Tel\u00e9fono - Whatsapp: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Whatsapp\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-phonetext wpcf7-text wpcf7-validates-as-phonetext\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Whatsapp\" \/><input type=\"hidden\" name=\"Whatsapp-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span>\n        <\/div>\n    <\/div>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Cantidad de Personas Adultas: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Adultos\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Adultos\"><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><option value=\"6\">6<\/option><option value=\"7\">7<\/option><option value=\"8\">8<\/option><option value=\"9\">9<\/option><option value=\"10\">10<\/option><option value=\"11\">11<\/option><option value=\"12 a m\u00e1s\">12 a m\u00e1s<\/option><\/select><\/span>\n        <\/div>\n        <div>\n            <label>Cantidad de Ni\u00f1os: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Ninos\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"Ninos\"><option value=\"0\">0<\/option><option value=\"1\">1<\/option><option value=\"2\">2<\/option><option value=\"3\">3<\/option><option value=\"4\">4<\/option><option value=\"5\">5<\/option><option value=\"6\">6<\/option><option value=\"7\">7<\/option><option value=\"8\">8<\/option><option value=\"9\">9<\/option><option value=\"10\">10<\/option><option value=\"11\">11<\/option><option value=\"12 a m\u00e1s\">12 a m\u00e1s<\/option><\/select><\/span>\n        <\/div>\n    <\/div>\n    \n    <div class=\"g2\">\n        <div>\n            <label>Fecha de Inicio del Tour: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Inicio\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" id=\"inicio\" min=\"2026-05-13\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"Inicio\" \/><\/span>\n        <\/div>\n        <div>\n            <label>Fecha de Finalizaci\u00f3n del Tour: <\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"Final\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" id=\"final\" min=\"2026-05-13\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"Final\" \/><\/span>\n        <\/div>\n    <\/div>\n    \n    <div>\n        <label>Comentarios o preguntas: <\/label>\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"Mensaje\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Por favor especifica el tipo de SERVICIO\/TOUR que deseas realizar\" name=\"Mensaje\"><\/textarea><\/span>\n    <\/div>\n    \n    <input class=\"wpcf7-form-control wpcf7-submit has-spinner btnsend\" type=\"submit\" value=\"ENVIAR MENSAJE\" \/>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nivel: challenge. Clase: r\u00e1pidos 4 y 5. No es necesaria experiencia previa, pero una buena condici\u00f3n f\u00edsica es esencial. A [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21382,"parent":3504,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-tour.php","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-12715","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo<\/title>\n<meta name=\"description\" content=\"La ciudad de Arequipa, en este tour haremos un viaje a Cotahuasi y los ba\u00f1os de Luicho, luego haremos rafting en el rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo\" \/>\n<meta property=\"og:description\" content=\"La ciudad de Arequipa, en este tour haremos un viaje a Cotahuasi y los ba\u00f1os de Luicho, luego haremos rafting en el rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Eric Adventures\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T16:32:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/\",\"url\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/\",\"name\":\"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo\",\"isPartOf\":{\"@id\":\"https:\/\/www.ericadventures.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg\",\"datePublished\":\"2024-02-23T15:29:44+00:00\",\"dateModified\":\"2025-11-05T16:32:23+00:00\",\"description\":\"La ciudad de Arequipa, en este tour haremos un viaje a Cotahuasi y los ba\u00f1os de Luicho, luego haremos rafting en el rio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#primaryimage\",\"url\":\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg\",\"contentUrl\":\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ericadventures.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tours en Cusco\",\"item\":\"https:\/\/www.ericadventures.com\/es\/cusco\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rafting\",\"item\":\"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ericadventures.com\/en\/#website\",\"url\":\"https:\/\/www.ericadventures.com\/en\/\",\"name\":\"Eric Adventures\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ericadventures.com\/en\/#organization\"},\"alternateName\":\"Eric Adventures\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ericadventures.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ericadventures.com\/en\/#organization\",\"name\":\"Eric Adventures\",\"url\":\"https:\/\/www.ericadventures.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ericadventures.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/logo-ericadventures.png\",\"contentUrl\":\"https:\/\/www.ericadventures.com\/wp-content\/uploads\/logo-ericadventures.png\",\"width\":500,\"height\":106,\"caption\":\"Eric Adventures\"},\"image\":{\"@id\":\"https:\/\/www.ericadventures.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo","description":"La ciudad de Arequipa, en este tour haremos un viaje a Cotahuasi y los ba\u00f1os de Luicho, luego haremos rafting en el rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/","og_locale":"es_ES","og_type":"article","og_title":"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo","og_description":"La ciudad de Arequipa, en este tour haremos un viaje a Cotahuasi y los ba\u00f1os de Luicho, luego haremos rafting en el rio.","og_url":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/","og_site_name":"Eric Adventures","article_modified_time":"2025-11-05T16:32:23+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/","url":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/","name":"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo","isPartOf":{"@id":"https:\/\/www.ericadventures.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#primaryimage"},"image":{"@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg","datePublished":"2024-02-23T15:29:44+00:00","dateModified":"2025-11-05T16:32:23+00:00","description":"La ciudad de Arequipa, en este tour haremos un viaje a Cotahuasi y los ba\u00f1os de Luicho, luego haremos rafting en el rio.","breadcrumb":{"@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#primaryimage","url":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg","contentUrl":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg","width":2560,"height":1707,"caption":"R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/rio-cotahuasi-canon-profundo-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ericadventures.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tours en Cusco","item":"https:\/\/www.ericadventures.com\/es\/cusco\/"},{"@type":"ListItem","position":3,"name":"Rafting","item":"https:\/\/www.ericadventures.com\/es\/cusco\/rafting\/"},{"@type":"ListItem","position":4,"name":"10D R\u00edo Cotahuasi El Ca\u00f1\u00f3n M\u00e1s Profundo Del Mundo"}]},{"@type":"WebSite","@id":"https:\/\/www.ericadventures.com\/en\/#website","url":"https:\/\/www.ericadventures.com\/en\/","name":"Eric Adventures","description":"","publisher":{"@id":"https:\/\/www.ericadventures.com\/en\/#organization"},"alternateName":"Eric Adventures","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ericadventures.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ericadventures.com\/en\/#organization","name":"Eric Adventures","url":"https:\/\/www.ericadventures.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ericadventures.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/logo-ericadventures.png","contentUrl":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/logo-ericadventures.png","width":500,"height":106,"caption":"Eric Adventures"},"image":{"@id":"https:\/\/www.ericadventures.com\/en\/#\/schema\/logo\/image\/"}}]}},"coauthors":[],"author_meta":{"author_link":"https:\/\/www.ericadventures.com\/es\/author\/marilyn\/","display_name":"Marilyn Ayma Gomez"},"relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 6 meses hace"},"absolute_dates":{"created":"Publicado el febrero 23, 2024","modified":"Actualizado el noviembre 5, 2025"},"absolute_dates_time":{"created":"Publicado el febrero 23, 2024 10:29 am","modified":"Actualizado el noviembre 5, 2025 11:32 am"},"featured_img_caption":"","featured_img":"https:\/\/www.ericadventures.com\/wp-content\/uploads\/WBN-41-1.jpg","series_order":"","_links":{"self":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/12715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/comments?post=12715"}],"version-history":[{"count":6,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/12715\/revisions"}],"predecessor-version":[{"id":42991,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/12715\/revisions\/42991"}],"up":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/pages\/3504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/media\/21382"}],"wp:attachment":[{"href":"https:\/\/www.ericadventures.com\/es\/wp-json\/wp\/v2\/media?parent=12715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}